{"id":639,"date":"2022-03-14T12:46:25","date_gmt":"2022-03-14T12:46:25","guid":{"rendered":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/"},"modified":"2022-03-14T12:46:25","modified_gmt":"2022-03-14T12:46:25","slug":"mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow","status":"publish","type":"post","link":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/","title":{"rendered":"Mandatory mask-wearing in public places to be abolished in Moscow"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[],"class_list":["post-639","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/\" \/>\n<meta property=\"og:site_name\" content=\"Armenia News\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-14T12:46:25+00:00\" \/>\n<meta name=\"author\" content=\"cldhaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cldhaz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/\"},\"author\":{\"name\":\"cldhaz\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/#\\\/schema\\\/person\\\/d0dde0bba99018a0ebe084fdd2187614\"},\"headline\":\"Mandatory mask-wearing in public places to be abolished in Moscow\",\"datePublished\":\"2022-03-14T12:46:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/\"},\"wordCount\":10,\"commentCount\":0,\"articleSection\":[\"Latest News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/\",\"url\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/\",\"name\":\"Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/#website\"},\"datePublished\":\"2022-03-14T12:46:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/#\\\/schema\\\/person\\\/d0dde0bba99018a0ebe084fdd2187614\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armenianews.me\\\/En\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mandatory mask-wearing in public places to be abolished in Moscow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/#website\",\"url\":\"https:\\\/\\\/armenianews.me\\\/En\\\/\",\"name\":\"Armenia News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armenianews.me\\\/En\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armenianews.me\\\/En\\\/#\\\/schema\\\/person\\\/d0dde0bba99018a0ebe084fdd2187614\",\"name\":\"cldhaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g\",\"caption\":\"cldhaz\"},\"url\":\"https:\\\/\\\/armenianews.me\\\/En\\\/author\\\/cldhaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/","og_locale":"en_US","og_type":"article","og_title":"Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News","og_url":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/","og_site_name":"Armenia News","article_published_time":"2022-03-14T12:46:25+00:00","author":"cldhaz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cldhaz"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/#article","isPartOf":{"@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/"},"author":{"name":"cldhaz","@id":"https:\/\/armenianews.me\/En\/#\/schema\/person\/d0dde0bba99018a0ebe084fdd2187614"},"headline":"Mandatory mask-wearing in public places to be abolished in Moscow","datePublished":"2022-03-14T12:46:25+00:00","mainEntityOfPage":{"@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/"},"wordCount":10,"commentCount":0,"articleSection":["Latest News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/","url":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/","name":"Mandatory mask-wearing in public places to be abolished in Moscow - Armenia News","isPartOf":{"@id":"https:\/\/armenianews.me\/En\/#website"},"datePublished":"2022-03-14T12:46:25+00:00","author":{"@id":"https:\/\/armenianews.me\/En\/#\/schema\/person\/d0dde0bba99018a0ebe084fdd2187614"},"breadcrumb":{"@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/armenianews.me\/En\/mandatory-mask-wearing-in-public-places-to-be-abolished-in-moscow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/armenianews.me\/En\/"},{"@type":"ListItem","position":2,"name":"Mandatory mask-wearing in public places to be abolished in Moscow"}]},{"@type":"WebSite","@id":"https:\/\/armenianews.me\/En\/#website","url":"https:\/\/armenianews.me\/En\/","name":"Armenia News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armenianews.me\/En\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/armenianews.me\/En\/#\/schema\/person\/d0dde0bba99018a0ebe084fdd2187614","name":"cldhaz","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18bf5a12d29ca7dd283a9ae2da7312d80733deab88692c92290f32fbb9e96f7b?s=96&d=mm&r=g","caption":"cldhaz"},"url":"https:\/\/armenianews.me\/En\/author\/cldhaz\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/posts\/639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/comments?post=639"}],"version-history":[{"count":0,"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/posts\/639\/revisions"}],"wp:attachment":[{"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/media?parent=639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/categories?post=639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armenianews.me\/En\/wp-json\/wp\/v2\/tags?post=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}